{"id":1499,"date":"2025-09-10T04:32:17","date_gmt":"2025-09-10T02:32:17","guid":{"rendered":"https:\/\/fitnessplayer.io\/book-a-demo\/"},"modified":"2025-11-18T13:34:15","modified_gmt":"2025-11-18T12:34:15","slug":"demo","status":"publish","type":"page","link":"https:\/\/fitnessplayer.io\/de\/demo\/","title":{"rendered":"Demo buchen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"ct-flexible-sections.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1499","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FitnessPlayer \u2013 Demo buchen<\/title>\n<meta name=\"description\" content=\"Buchen Sie eine pers\u00f6nliche Demo und entdecken Sie, wie FitnessPlayer Ihre Einrichtung mit lizenzierter Musik unterst\u00fctzen kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fitnessplayer.io\/de\/demo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FitnessPlayer \u2013 Demo buchen\" \/>\n<meta property=\"og:description\" content=\"Buchen Sie eine pers\u00f6nliche Demo und entdecken Sie, wie FitnessPlayer Ihre Einrichtung mit lizenzierter Musik unterst\u00fctzen kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fitnessplayer.io\/de\/demo\/\" \/>\n<meta property=\"og:site_name\" content=\"FitnessPlayer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myfitnessplayer\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T12:34:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/demo\\\/\",\"url\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/demo\\\/\",\"name\":\"FitnessPlayer \u2013 Demo buchen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/#website\"},\"datePublished\":\"2025-09-10T02:32:17+00:00\",\"dateModified\":\"2025-11-18T12:34:15+00:00\",\"description\":\"Buchen Sie eine pers\u00f6nliche Demo und entdecken Sie, wie FitnessPlayer Ihre Einrichtung mit lizenzierter Musik unterst\u00fctzen kann.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/demo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/demo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/demo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demo buchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/\",\"name\":\"FitnessPlayer\",\"description\":\"Music for gyms &amp; instructors\",\"publisher\":{\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/#organization\",\"name\":\"FitnessPlayer\",\"url\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fitnessplayer.io\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/fitnessplayer.io\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"width\":628,\"height\":176,\"caption\":\"FitnessPlayer\"},\"image\":{\"@id\":\"https:\\\/\\\/fitnessplayer.io\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/myfitnessplayer\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fitnessplayer_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fitnessplayer\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FitnessPlayer \u2013 Demo buchen","description":"Buchen Sie eine pers\u00f6nliche Demo und entdecken Sie, wie FitnessPlayer Ihre Einrichtung mit lizenzierter Musik unterst\u00fctzen kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fitnessplayer.io\/de\/demo\/","og_locale":"de_DE","og_type":"article","og_title":"FitnessPlayer \u2013 Demo buchen","og_description":"Buchen Sie eine pers\u00f6nliche Demo und entdecken Sie, wie FitnessPlayer Ihre Einrichtung mit lizenzierter Musik unterst\u00fctzen kann.","og_url":"https:\/\/fitnessplayer.io\/de\/demo\/","og_site_name":"FitnessPlayer","article_publisher":"https:\/\/www.facebook.com\/myfitnessplayer\/","article_modified_time":"2025-11-18T12:34:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fitnessplayer.io\/de\/demo\/","url":"https:\/\/fitnessplayer.io\/de\/demo\/","name":"FitnessPlayer \u2013 Demo buchen","isPartOf":{"@id":"https:\/\/fitnessplayer.io\/de\/#website"},"datePublished":"2025-09-10T02:32:17+00:00","dateModified":"2025-11-18T12:34:15+00:00","description":"Buchen Sie eine pers\u00f6nliche Demo und entdecken Sie, wie FitnessPlayer Ihre Einrichtung mit lizenzierter Musik unterst\u00fctzen kann.","breadcrumb":{"@id":"https:\/\/fitnessplayer.io\/de\/demo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fitnessplayer.io\/de\/demo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fitnessplayer.io\/de\/demo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fitnessplayer.io\/de\/"},{"@type":"ListItem","position":2,"name":"Demo buchen"}]},{"@type":"WebSite","@id":"https:\/\/fitnessplayer.io\/de\/#website","url":"https:\/\/fitnessplayer.io\/de\/","name":"FitnessPlayer","description":"Music for gyms &amp; instructors","publisher":{"@id":"https:\/\/fitnessplayer.io\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fitnessplayer.io\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fitnessplayer.io\/de\/#organization","name":"FitnessPlayer","url":"https:\/\/fitnessplayer.io\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fitnessplayer.io\/de\/#\/schema\/logo\/image\/","url":"https:\/\/fitnessplayer.io\/wp-content\/uploads\/2025\/07\/logo.png","contentUrl":"https:\/\/fitnessplayer.io\/wp-content\/uploads\/2025\/07\/logo.png","width":628,"height":176,"caption":"FitnessPlayer"},"image":{"@id":"https:\/\/fitnessplayer.io\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/myfitnessplayer\/","https:\/\/www.instagram.com\/fitnessplayer_\/","https:\/\/www.linkedin.com\/company\/fitnessplayer\/"]}]}},"_links":{"self":[{"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/pages\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":3,"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/pages\/1499\/revisions"}],"predecessor-version":[{"id":2147,"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/pages\/1499\/revisions\/2147"}],"wp:attachment":[{"href":"https:\/\/fitnessplayer.io\/de\/wp-json\/wp\/v2\/media?parent=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}